{"id":2734,"date":"2025-05-12T16:07:05","date_gmt":"2025-05-12T16:07:05","guid":{"rendered":"https:\/\/oberholz.com\/?post_type=event&#038;p=2734"},"modified":"2026-04-27T09:49:11","modified_gmt":"2026-04-27T09:49:11","slug":"fruehstueck-auf-der-berghuette-oberholz-auf-2096-m","status":"publish","type":"event","link":"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/","title":{"rendered":"Fr\u00fchst\u00fcck auf der Bergh\u00fctte Oberholz auf 2.096 m"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Das w\u00f6chentliche Highlight unterm Latemar findet jeden Donnerstag und Samstag von 8:30 bis 10:00 Uhr statt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das umfangreiche Genusserlebnis \u201eFr\u00fchst\u00fcck auf der Oberholz\u201c inklusive der Berg- und Talfahrt kostet f\u00fcr Erwachsene 36 Euro, Jugendliche unter 12 Jahren bezahlen 29 Euro, Kinder bis 5 Jahre sind kostenlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zur Bergh\u00fctte und zur\u00fcck ins Tal geht es mit dem Panorama-Sessellift Obereggen-Oberholz (Auffahrt ab 08:30, letzte R\u00fcckfahrt 18.00 Uhr).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Reservierung ist erforderlich: <a href=\"mailto:oberholz@latemar.it\">oberholz@latemar.it<\/a>&nbsp;0471 618299<\/p>\n","protected":false},"featured_media":342,"template":"","tags":[58],"class_list":["post-2734","event","type-event","status-publish","has-post-thumbnail","hentry","tag-active-de-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fr\u00fchst\u00fcck auf der Bergh\u00fctte Oberholz auf 2.096 m - Oberholz H\u00fctte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fr\u00fchst\u00fcck auf der Bergh\u00fctte Oberholz auf 2.096 m - Oberholz H\u00fctte\" \/>\n<meta property=\"og:description\" content=\"Das w\u00f6chentliche Highlight unterm Latemar findet jeden Donnerstag und Samstag von 8:30 bis 10:00 Uhr statt. Das umfangreiche Genusserlebnis \u201eFr\u00fchst\u00fcck auf der Oberholz\u201c inklusive der Berg- und Talfahrt kostet f\u00fcr Erwachsene 36 Euro, Jugendliche unter 12 Jahren bezahlen 29 Euro, Kinder bis 5 Jahre sind kostenlos. Zur Bergh\u00fctte und zur\u00fcck ins Tal geht es mit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/\" \/>\n<meta property=\"og:site_name\" content=\"Oberholz H\u00fctte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OberholzDolomites\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T09:49:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oberholz.com\/wp-content\/uploads\/2025\/02\/DSC04649.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1333\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oberholz.com\\\/de\\\/event\\\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\\\/\",\"url\":\"https:\\\/\\\/oberholz.com\\\/de\\\/event\\\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\\\/\",\"name\":\"Fr\u00fchst\u00fcck auf der Bergh\u00fctte Oberholz auf 2.096 m - Oberholz H\u00fctte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oberholz.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oberholz.com\\\/de\\\/event\\\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oberholz.com\\\/de\\\/event\\\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oberholz.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/DSC04649.jpg\",\"datePublished\":\"2025-05-12T16:07:05+00:00\",\"dateModified\":\"2026-04-27T09:49:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oberholz.com\\\/de\\\/event\\\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oberholz.com\\\/de\\\/event\\\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/oberholz.com\\\/de\\\/event\\\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\\\/#primaryimage\",\"url\":\"https:\\\/\\\/oberholz.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/DSC04649.jpg\",\"contentUrl\":\"https:\\\/\\\/oberholz.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/DSC04649.jpg\",\"width\":1333,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oberholz.com\\\/de\\\/event\\\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/oberholz.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/oberholz.com\\\/it\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fr\u00fchst\u00fcck auf der Bergh\u00fctte Oberholz auf 2.096 m\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oberholz.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/oberholz.com\\\/it\\\/\",\"name\":\"Rifugio Oberholz\",\"description\":\"Genuss auf 2.096 m\",\"publisher\":{\"@id\":\"https:\\\/\\\/oberholz.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oberholz.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oberholz.com\\\/it\\\/#organization\",\"name\":\"Rifugio Oberholz\",\"url\":\"https:\\\/\\\/oberholz.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/oberholz.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oberholz.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-oberholz-color-variant-no-stamp.svg\",\"contentUrl\":\"https:\\\/\\\/oberholz.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-oberholz-color-variant-no-stamp.svg\",\"width\":174,\"height\":175,\"caption\":\"Rifugio Oberholz\"},\"image\":{\"@id\":\"https:\\\/\\\/oberholz.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OberholzDolomites\\\/\",\"https:\\\/\\\/www.instagram.com\\\/oberholz_dolomites\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fr\u00fchst\u00fcck auf der Bergh\u00fctte Oberholz auf 2.096 m - Oberholz H\u00fctte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/","og_locale":"de_DE","og_type":"article","og_title":"Fr\u00fchst\u00fcck auf der Bergh\u00fctte Oberholz auf 2.096 m - Oberholz H\u00fctte","og_description":"Das w\u00f6chentliche Highlight unterm Latemar findet jeden Donnerstag und Samstag von 8:30 bis 10:00 Uhr statt. Das umfangreiche Genusserlebnis \u201eFr\u00fchst\u00fcck auf der Oberholz\u201c inklusive der Berg- und Talfahrt kostet f\u00fcr Erwachsene 36 Euro, Jugendliche unter 12 Jahren bezahlen 29 Euro, Kinder bis 5 Jahre sind kostenlos. Zur Bergh\u00fctte und zur\u00fcck ins Tal geht es mit [&hellip;]","og_url":"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/","og_site_name":"Oberholz H\u00fctte","article_publisher":"https:\/\/www.facebook.com\/OberholzDolomites\/","article_modified_time":"2026-04-27T09:49:11+00:00","og_image":[{"width":1333,"height":2000,"url":"https:\/\/oberholz.com\/wp-content\/uploads\/2025\/02\/DSC04649.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/","url":"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/","name":"Fr\u00fchst\u00fcck auf der Bergh\u00fctte Oberholz auf 2.096 m - Oberholz H\u00fctte","isPartOf":{"@id":"https:\/\/oberholz.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/#primaryimage"},"image":{"@id":"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/#primaryimage"},"thumbnailUrl":"https:\/\/oberholz.com\/wp-content\/uploads\/2025\/02\/DSC04649.jpg","datePublished":"2025-05-12T16:07:05+00:00","dateModified":"2026-04-27T09:49:11+00:00","breadcrumb":{"@id":"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/#primaryimage","url":"https:\/\/oberholz.com\/wp-content\/uploads\/2025\/02\/DSC04649.jpg","contentUrl":"https:\/\/oberholz.com\/wp-content\/uploads\/2025\/02\/DSC04649.jpg","width":1333,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/oberholz.com\/de\/event\/fruehstueck-auf-der-berghuette-oberholz-auf-2096-m\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oberholz.com\/de\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/oberholz.com\/it\/event\/"},{"@type":"ListItem","position":3,"name":"Fr\u00fchst\u00fcck auf der Bergh\u00fctte Oberholz auf 2.096 m"}]},{"@type":"WebSite","@id":"https:\/\/oberholz.com\/it\/#website","url":"https:\/\/oberholz.com\/it\/","name":"Rifugio Oberholz","description":"Genuss auf 2.096 m","publisher":{"@id":"https:\/\/oberholz.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oberholz.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/oberholz.com\/it\/#organization","name":"Rifugio Oberholz","url":"https:\/\/oberholz.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/oberholz.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/oberholz.com\/wp-content\/uploads\/2025\/02\/logo-oberholz-color-variant-no-stamp.svg","contentUrl":"https:\/\/oberholz.com\/wp-content\/uploads\/2025\/02\/logo-oberholz-color-variant-no-stamp.svg","width":174,"height":175,"caption":"Rifugio Oberholz"},"image":{"@id":"https:\/\/oberholz.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OberholzDolomites\/","https:\/\/www.instagram.com\/oberholz_dolomites\/"]}]}},"meta_box":{"subtitle":"Jeden Donnerstag und Samstag"},"_links":{"self":[{"href":"https:\/\/oberholz.com\/de\/wp-json\/wp\/v2\/event\/2734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oberholz.com\/de\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/oberholz.com\/de\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oberholz.com\/de\/wp-json\/wp\/v2\/media\/342"}],"wp:attachment":[{"href":"https:\/\/oberholz.com\/de\/wp-json\/wp\/v2\/media?parent=2734"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oberholz.com\/de\/wp-json\/wp\/v2\/tags?post=2734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}